{"id":12204,"date":"2026-03-24T20:15:38","date_gmt":"2026-03-24T23:15:38","guid":{"rendered":"https:\/\/lackman.com.br\/?p=12204"},"modified":"2026-03-27T20:41:36","modified_gmt":"2026-03-27T23:41:36","slug":"nao-perca-a-floresta-viva-do-pontao","status":"publish","type":"post","link":"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/","title":{"rendered":"N\u00e3o perca a \u201cFloresta Viva\u201d do Pont\u00e3o!"},"content":{"rendered":"<h5 style=\"text-align: justify\"><em>Com programa\u00e7\u00e3o especial, o complexo recebe decora\u00e7\u00e3o tem\u00e1tica, oficinas infantis, espet\u00e1culos teatrais e experi\u00eancias imersivas para toda a fam\u00edlia.<\/em><\/h5>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">At\u00e9 5 de abril, o <a href=\"https:\/\/www.instagram.com\/pontaodolagosul\/?hl=pt\"><strong>Pont\u00e3o Lago Sul<\/strong><\/a> se transforma em um cen\u00e1rio m\u00e1gico com a chegada da \u201c<em><strong>Floresta Viva<\/strong><\/em>\u201d, tema da programa\u00e7\u00e3o especial de P\u00e1scoa de 2026. Inspirado na natureza, o espa\u00e7o ganha uma ambienta\u00e7\u00e3o l\u00fadica e envolvente, com elementos que remetem ao universo encantado da floresta, proporcionando momentos inesquec\u00edveis para visitantes de todas as idades.<\/p>\n<p style=\"text-align: justify\">No Jardim de Eventos, uma floresta decorada com \u00e1rvores cenogr\u00e1ficas, cogumelos e coelhos em uma paleta de tons verdes e terrosos que refor\u00e7am a proposta de conex\u00e3o com a natureza. O ambiente convida o p\u00fablico a vivenciar uma experi\u00eancia sensorial acolhedora, ideal para fam\u00edlias e crian\u00e7as.<\/p>\n<p style=\"text-align: justify\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-12207 size-full\" src=\"http:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-13-1536x1011-1.png\" alt=\"\" width=\"1536\" height=\"1011\" srcset=\"https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-13-1536x1011-1.png 1536w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-13-1536x1011-1-300x197.png 300w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-13-1536x1011-1-1024x674.png 1024w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-13-1536x1011-1-768x506.png 768w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-13-1536x1011-1-100x66.png 100w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><\/p>\n<p style=\"text-align: justify\">A grande atra\u00e7\u00e3o deste ano \u00e9 a Toca Encantada, um espa\u00e7o coberto e imersivo, com decora\u00e7\u00e3o especial e cen\u00e1rios instagram\u00e1veis, incluindo elementos como o guardi\u00e3o da floresta, \u00e1rvores e ambienta\u00e7\u00f5es m\u00e1gicas. O acesso \u00e0 \u00e1rea \u00e9 exclusivo para visitantes mediante ingresso. Meia-entrada R$ 20,00 e ingresso inteiro a R$ 40,00 por pessoa. Crian\u00e7as de at\u00e9 8 anos tem entrada gratuita. Meia-entrada mediante a doa\u00e7\u00e3o de 1kg de alimento a ser destinado \u00e0 Vila Santa Luzia na Estrutural em parceria com o grupo Panelas Compartilhadas.<\/p>\n<p style=\"text-align: justify\">Os ingressos poder\u00e3o ser adquiridos na loja do Pont\u00e3o situada na Floresta Viva, ou nos restaurantes e quiosques do Pont\u00e3o Lago Sul participantes da a\u00e7\u00e3o, estes com retiradas gratuitas mediante notas fiscais com valor m\u00ednimo de consuma\u00e7\u00e3o de R$150,00, para restaurantes, e R$50,00 para quiosques participantes.<\/p>\n<p style=\"text-align: justify\"><img decoding=\"async\" class=\"aligncenter wp-image-12206 size-full\" src=\"http:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-5-1536x1011-1.png\" alt=\"\" width=\"1536\" height=\"1011\" srcset=\"https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-5-1536x1011-1.png 1536w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-5-1536x1011-1-300x197.png 300w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-5-1536x1011-1-1024x674.png 1024w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-5-1536x1011-1-768x506.png 768w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-5-1536x1011-1-100x66.png 100w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><\/p>\n<p style=\"text-align: justify\"><strong>Programa\u00e7\u00e3o cultural<\/strong><\/p>\n<p style=\"text-align: justify\">Al\u00e9m da decora\u00e7\u00e3o tem\u00e1tica, o p\u00fablico poder\u00e1 aproveitar uma programa\u00e7\u00e3o completa com espet\u00e1culos teatrais, oficinas criativas e apresenta\u00e7\u00f5es musicais. Entre os destaques est\u00e3o as pe\u00e7as infantis realizadas \u00e0s ter\u00e7as e quintas-feiras, das 18h30 \u00e0s 19h30, com entrada mediante doa\u00e7\u00e3o de 1kg de alimento n\u00e3o perec\u00edvel (exceto sal, floc\u00e3o e \u00e1gua pot\u00e1vel) destinado \u00e0 Vila Santa Luzia, na Estrutural, em parceria com o grupo Panelas Compartilhadas.<\/p>\n<p style=\"text-align: justify\">As apresenta\u00e7\u00f5es trazem hist\u00f3rias leves, educativas e interativas, abordando valores como amizade, coopera\u00e7\u00e3o e o verdadeiro significado da P\u00e1scoa. A programa\u00e7\u00e3o inclui ainda o Musical P\u00e1scoa Broadway, com apresenta\u00e7\u00e3o no dia 20 de mar\u00e7o, \u00e0s 19h30, marcando a abertura oficial do evento.<\/p>\n<p style=\"text-align: justify\"><strong>24\/03 &#8211; P\u00e1scoa no S\u00edtio<\/strong><\/p>\n<p style=\"text-align: justify\">No clima acolhedor do campo, personagens queridos vivem uma aventura divertida para salvar a celebra\u00e7\u00e3o da P\u00e1scoa. Uma hist\u00f3ria leve, educativa e interativa. Apresenta\u00e7\u00e3o grupo Starter Entretenimentos.<\/p>\n<p style=\"text-align: justify\"><strong>26\/03 &#8211; O segredo da P\u00e1scoa<\/strong><\/p>\n<p style=\"text-align: justify\">Um casal de coelhos muito animado est\u00e1 preocupado com a chegada da P\u00e1scoa pois ainda falta muita coisa para arrumar. Essa dupla encantadora conta atrav\u00e9s de muita dan\u00e7a, m\u00fasica e teatro a verdadeira hist\u00f3ria da P\u00e1scoa! Apresenta\u00e7\u00e3o grupo Oja Lai\u00f3.<\/p>\n<p style=\"text-align: justify\"><strong>31\/03 &#8211; O coelhinho Comil\u00e3o<\/strong><\/p>\n<p style=\"text-align: justify\">P\u00e1scoa est\u00e1 chegando e a f\u00e1brica de ovos de chocolate est\u00e1 a todo vapor para entregar suas encomendas para as crian\u00e7as. S\u00f3 que parece que a produ\u00e7\u00e3o n\u00e3o tem fim, alguns ovos est\u00e3o sumindo. O que ser\u00e1 que o assistente do Coelho da P\u00e1scoa est\u00e1 justificando? Apresenta\u00e7\u00e3o grupo Neia e Nando.<\/p>\n<p style=\"text-align: justify\"><img decoding=\"async\" class=\"aligncenter wp-image-12208 size-full\" src=\"http:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-30-1536x1024-1.png\" alt=\"\" width=\"1536\" height=\"1024\" srcset=\"https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-30-1536x1024-1.png 1536w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-30-1536x1024-1-300x200.png 300w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-30-1536x1024-1-1024x683.png 1024w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-30-1536x1024-1-768x512.png 768w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-30-1536x1024-1-100x67.png 100w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><\/p>\n<p style=\"text-align: justify\"><strong>02\/04 &#8211; Fant\u00e1stica F\u00e1brica de Chocolate<\/strong><\/p>\n<p style=\"text-align: justify\">Uma jornada encantadora dentro de uma f\u00e1brica cheia de surpresa, m\u00fasicas e personagens exc\u00eantricos. Um espet\u00e1culo grandioso, visualmente impactante e com forte apelo familiar. Apresenta\u00e7\u00e3o grupo Starter Entretenimentos.<\/p>\n<p style=\"text-align: justify\"><strong>Oficinas <\/strong><\/p>\n<p style=\"text-align: justify\">Para completar a experi\u00eancia, as oficinas infantis acontecem diariamente, das 16h \u00e0s 22h, com atividades voltadas para crian\u00e7as de 3 a 14 anos. Entre as op\u00e7\u00f5es est\u00e3o pintura em tela, customiza\u00e7\u00e3o de coelhos de gesso, slime, jardinagem e cria\u00e7\u00e3o de um \u201camigo coelho\u201d para levar para casa. As atividades t\u00eam valor de R$ 50,00 por crian\u00e7a.<\/p>\n<p style=\"text-align: justify\">Entre as oficinas dispon\u00edveis est\u00e3o: Coelho de gesso (pintura e personaliza\u00e7\u00e3o de coelhinhos de P\u00e1scoa), Pintura em tela (pequenos artistas criando suas pr\u00f3prias obras), Slime (oficina divertida para produzir e brincar com slime), Cria Amigo Coelho (cria\u00e7\u00e3o de um coelhinho especial para levar para casa) e Jardinagem (plantio e cuidados com pequenas mudas).<\/p>\n<p style=\"text-align: justify\">Agora confira cliques de C\u00e9sar Rebou\u00e7as de alguns dos convidados especiais do Pont\u00e3o do Lago Sul que participaram da noite de abertura dessa &#8220;Floresta Viva&#8221;:<\/p>\n<figure id=\"attachment_12209\" aria-describedby=\"caption-attachment-12209\" style=\"width: 1536px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12209 size-full\" src=\"http:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Fabiana-Pinheiro-Enrico-Crosara-Vitor-Correa-Anagelica-Rodrigues-e-Lidia-Alves-1536x1024-1.png\" alt=\"\" width=\"1536\" height=\"1024\" srcset=\"https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Fabiana-Pinheiro-Enrico-Crosara-Vitor-Correa-Anagelica-Rodrigues-e-Lidia-Alves-1536x1024-1.png 1536w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Fabiana-Pinheiro-Enrico-Crosara-Vitor-Correa-Anagelica-Rodrigues-e-Lidia-Alves-1536x1024-1-300x200.png 300w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Fabiana-Pinheiro-Enrico-Crosara-Vitor-Correa-Anagelica-Rodrigues-e-Lidia-Alves-1536x1024-1-1024x683.png 1024w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Fabiana-Pinheiro-Enrico-Crosara-Vitor-Correa-Anagelica-Rodrigues-e-Lidia-Alves-1536x1024-1-768x512.png 768w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Fabiana-Pinheiro-Enrico-Crosara-Vitor-Correa-Anagelica-Rodrigues-e-Lidia-Alves-1536x1024-1-100x67.png 100w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><figcaption id=\"caption-attachment-12209\" class=\"wp-caption-text\">Fabiana Pinheiro, Enricco Crosara, Vitor Corr\u00eaa, Anag\u00e9lica Rodrigues e Lidia Alves<\/figcaption><\/figure>\n<figure id=\"attachment_12216\" aria-describedby=\"caption-attachment-12216\" style=\"width: 1536px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12216 size-full\" src=\"http:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Nina-e-Eliane-Rocha-2-1536x1024-1.png\" alt=\"\" width=\"1536\" height=\"1024\" srcset=\"https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Nina-e-Eliane-Rocha-2-1536x1024-1.png 1536w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Nina-e-Eliane-Rocha-2-1536x1024-1-300x200.png 300w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Nina-e-Eliane-Rocha-2-1536x1024-1-1024x683.png 1024w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Nina-e-Eliane-Rocha-2-1536x1024-1-768x512.png 768w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Nina-e-Eliane-Rocha-2-1536x1024-1-100x67.png 100w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><figcaption id=\"caption-attachment-12216\" class=\"wp-caption-text\">Nina e Eliane Rocha<\/figcaption><\/figure>\n<figure id=\"attachment_12211\" aria-describedby=\"caption-attachment-12211\" style=\"width: 1536px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12211 size-full\" src=\"http:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Alice-Varela-Isadora-e-Ludmila-Sa-Teles-1536x1024-1.png\" alt=\"\" width=\"1536\" height=\"1024\" srcset=\"https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Alice-Varela-Isadora-e-Ludmila-Sa-Teles-1536x1024-1.png 1536w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Alice-Varela-Isadora-e-Ludmila-Sa-Teles-1536x1024-1-300x200.png 300w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Alice-Varela-Isadora-e-Ludmila-Sa-Teles-1536x1024-1-1024x683.png 1024w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Alice-Varela-Isadora-e-Ludmila-Sa-Teles-1536x1024-1-768x512.png 768w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Alice-Varela-Isadora-e-Ludmila-Sa-Teles-1536x1024-1-100x67.png 100w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><figcaption id=\"caption-attachment-12211\" class=\"wp-caption-text\">Alice Varela, Isadora e Ludmila S\u00e1 Teles<\/figcaption><\/figure>\n<figure id=\"attachment_12212\" aria-describedby=\"caption-attachment-12212\" style=\"width: 1536px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12212 size-full\" src=\"http:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Gabriela-Louredo-e-Aggda-Mila-2-1536x1024-1.png\" alt=\"\" width=\"1536\" height=\"1024\" srcset=\"https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Gabriela-Louredo-e-Aggda-Mila-2-1536x1024-1.png 1536w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Gabriela-Louredo-e-Aggda-Mila-2-1536x1024-1-300x200.png 300w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Gabriela-Louredo-e-Aggda-Mila-2-1536x1024-1-1024x683.png 1024w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Gabriela-Louredo-e-Aggda-Mila-2-1536x1024-1-768x512.png 768w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Gabriela-Louredo-e-Aggda-Mila-2-1536x1024-1-100x67.png 100w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><figcaption id=\"caption-attachment-12212\" class=\"wp-caption-text\">Gabriela Louredo e Aggda Mila<\/figcaption><\/figure>\n<figure id=\"attachment_12213\" aria-describedby=\"caption-attachment-12213\" style=\"width: 1536px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12213 size-full\" src=\"http:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Gilberto-Evangelista-e-Gustavo-Roccha-2-1536x1016-1.png\" alt=\"\" width=\"1536\" height=\"1016\" srcset=\"https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Gilberto-Evangelista-e-Gustavo-Roccha-2-1536x1016-1.png 1536w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Gilberto-Evangelista-e-Gustavo-Roccha-2-1536x1016-1-300x198.png 300w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Gilberto-Evangelista-e-Gustavo-Roccha-2-1536x1016-1-1024x677.png 1024w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Gilberto-Evangelista-e-Gustavo-Roccha-2-1536x1016-1-768x508.png 768w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Gilberto-Evangelista-e-Gustavo-Roccha-2-1536x1016-1-100x66.png 100w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><figcaption id=\"caption-attachment-12213\" class=\"wp-caption-text\">Gilberto Evangelista e Gustavo Roccha<\/figcaption><\/figure>\n<figure id=\"attachment_12214\" aria-describedby=\"caption-attachment-12214\" style=\"width: 1536px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12214 size-full\" src=\"http:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Ivone-Carvalho-1536x1024-1.png\" alt=\"\" width=\"1536\" height=\"1024\" srcset=\"https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Ivone-Carvalho-1536x1024-1.png 1536w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Ivone-Carvalho-1536x1024-1-300x200.png 300w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Ivone-Carvalho-1536x1024-1-1024x683.png 1024w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Ivone-Carvalho-1536x1024-1-768x512.png 768w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Ivone-Carvalho-1536x1024-1-100x67.png 100w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><figcaption id=\"caption-attachment-12214\" class=\"wp-caption-text\">Ivone Carvalho com os anfitri\u00f5es da festa<\/figcaption><\/figure>\n<figure id=\"attachment_12215\" aria-describedby=\"caption-attachment-12215\" style=\"width: 1536px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12215 size-full\" src=\"http:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Marcos-Ribeiro-Lander-Pio-e-Wanderson-Costa-1536x1024-1.png\" alt=\"\" width=\"1536\" height=\"1024\" srcset=\"https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Marcos-Ribeiro-Lander-Pio-e-Wanderson-Costa-1536x1024-1.png 1536w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Marcos-Ribeiro-Lander-Pio-e-Wanderson-Costa-1536x1024-1-300x200.png 300w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Marcos-Ribeiro-Lander-Pio-e-Wanderson-Costa-1536x1024-1-1024x683.png 1024w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Marcos-Ribeiro-Lander-Pio-e-Wanderson-Costa-1536x1024-1-768x512.png 768w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Marcos-Ribeiro-Lander-Pio-e-Wanderson-Costa-1536x1024-1-100x67.png 100w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><figcaption id=\"caption-attachment-12215\" class=\"wp-caption-text\">Marcos Ribeiro, Lander Pio e Wanderson Costa<\/figcaption><\/figure>\n<figure id=\"attachment_12217\" aria-describedby=\"caption-attachment-12217\" style=\"width: 1536px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12217 size-full\" src=\"http:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Sabrinna-Albert-e-Mateus-Aragao-1-1536x1024-1.png\" alt=\"\" width=\"1536\" height=\"1024\" srcset=\"https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Sabrinna-Albert-e-Mateus-Aragao-1-1536x1024-1.png 1536w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Sabrinna-Albert-e-Mateus-Aragao-1-1536x1024-1-300x200.png 300w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Sabrinna-Albert-e-Mateus-Aragao-1-1536x1024-1-1024x683.png 1024w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Sabrinna-Albert-e-Mateus-Aragao-1-1536x1024-1-768x512.png 768w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Sabrinna-Albert-e-Mateus-Aragao-1-1536x1024-1-100x67.png 100w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><figcaption id=\"caption-attachment-12217\" class=\"wp-caption-text\">Mateus Arag\u00e3o e Sabrinna Albert<\/figcaption><\/figure>\n<figure id=\"attachment_12218\" aria-describedby=\"caption-attachment-12218\" style=\"width: 1536px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12218 size-full\" src=\"http:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Ray-Bendor-Flavio-Queiroz-e-Ana-Luiza-1536x1011-1.png\" alt=\"\" width=\"1536\" height=\"1011\" srcset=\"https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Ray-Bendor-Flavio-Queiroz-e-Ana-Luiza-1536x1011-1.png 1536w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Ray-Bendor-Flavio-Queiroz-e-Ana-Luiza-1536x1011-1-300x197.png 300w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Ray-Bendor-Flavio-Queiroz-e-Ana-Luiza-1536x1011-1-1024x674.png 1024w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Ray-Bendor-Flavio-Queiroz-e-Ana-Luiza-1536x1011-1-768x506.png 768w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Ray-Bendor-Flavio-Queiroz-e-Ana-Luiza-1536x1011-1-100x66.png 100w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><figcaption id=\"caption-attachment-12218\" class=\"wp-caption-text\">Ray Bendor, Fl\u00e1vio Queiroz e Ana Lu<\/figcaption><\/figure>\n<figure id=\"attachment_12210\" aria-describedby=\"caption-attachment-12210\" style=\"width: 1536px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12210 size-full\" src=\"http:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Adriana-Nasser-com-Bella-e-Luca-Petrarca-1536x1024-1.png\" alt=\"\" width=\"1536\" height=\"1024\" srcset=\"https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Adriana-Nasser-com-Bella-e-Luca-Petrarca-1536x1024-1.png 1536w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Adriana-Nasser-com-Bella-e-Luca-Petrarca-1536x1024-1-300x200.png 300w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Adriana-Nasser-com-Bella-e-Luca-Petrarca-1536x1024-1-1024x683.png 1024w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Adriana-Nasser-com-Bella-e-Luca-Petrarca-1536x1024-1-768x512.png 768w, https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/Adriana-Nasser-com-Bella-e-Luca-Petrarca-1536x1024-1-100x67.png 100w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><figcaption id=\"caption-attachment-12210\" class=\"wp-caption-text\">Adriana Nasser com Bella e Luca Petrarca<\/figcaption><\/figure>\n<p style=\"text-align: justify\"><em><b>Chocolate e divers\u00e3o!<\/b><\/em><\/p>\n<p style=\"text-align: justify\"><em><strong>P\u00e1scoa Floresta Viva do Pont\u00e3o Lago Sul <\/strong>\/ SHIS Ql 10, Lote 1\/30 Lago Sul &#8211; Bras\u00edlia \u2013 DF \u00a0\/ 20 de mar\u00e7o a 05 de abril \/\u00a0Telefone: (61) 3364-0580 \/ <a href=\"https:\/\/www.instagram.com\/pontaodolagosul\/?hl=pt\">@pontaodolagosul<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com programa\u00e7\u00e3o especial, o complexo recebe decora\u00e7\u00e3o tem\u00e1tica, oficinas infantis, espet\u00e1culos teatrais e experi\u00eancias imersivas para toda a fam\u00edlia. At\u00e9 5 de abril, o Pont\u00e3o Lago Sul se transforma em um cen\u00e1rio m\u00e1gico com a chegada da \u201cFloresta Viva\u201d, tema da programa\u00e7\u00e3o especial de P\u00e1scoa de 2026. Inspirado na natureza, o espa\u00e7o ganha uma ambienta\u00e7\u00e3o l\u00fadica e envolvente, com elementos que remetem ao universo encantado da floresta, proporcionando momentos inesquec\u00edveis para visitantes de todas as idades. No Jardim de Eventos, uma floresta decorada com \u00e1rvores cenogr\u00e1ficas, cogumelos e coelhos em uma paleta de tons verdes e terrosos que refor\u00e7am a proposta de conex\u00e3o com a natureza. O ambiente convida o p\u00fablico a vivenciar uma experi\u00eancia sensorial acolhedora, ideal para fam\u00edlias e crian\u00e7as. A grande atra\u00e7\u00e3o deste ano \u00e9 a Toca Encantada, um espa\u00e7o coberto e imersivo, com decora\u00e7\u00e3o especial e cen\u00e1rios instagram\u00e1veis, incluindo elementos como o guardi\u00e3o da floresta, \u00e1rvores e ambienta\u00e7\u00f5es m\u00e1gicas. O acesso \u00e0 \u00e1rea \u00e9 exclusivo para visitantes mediante ingresso. Meia-entrada R$ 20,00 e ingresso inteiro a R$ 40,00 por pessoa. Crian\u00e7as de at\u00e9 8 anos tem entrada gratuita. Meia-entrada mediante a doa\u00e7\u00e3o de 1kg de alimento a ser destinado \u00e0 Vila Santa Luzia na Estrutural em parceria com o grupo Panelas Compartilhadas. Os ingressos poder\u00e3o ser adquiridos na loja do Pont\u00e3o situada na Floresta Viva, ou nos restaurantes e quiosques do Pont\u00e3o Lago Sul participantes da a\u00e7\u00e3o, estes com retiradas gratuitas mediante notas fiscais com valor m\u00ednimo de consuma\u00e7\u00e3o de R$150,00, para restaurantes, e R$50,00 para quiosques participantes. Programa\u00e7\u00e3o cultural Al\u00e9m da decora\u00e7\u00e3o tem\u00e1tica, o p\u00fablico poder\u00e1 aproveitar uma programa\u00e7\u00e3o completa com espet\u00e1culos teatrais, oficinas criativas e apresenta\u00e7\u00f5es musicais. Entre os destaques est\u00e3o as pe\u00e7as infantis realizadas \u00e0s ter\u00e7as e quintas-feiras, das 18h30 \u00e0s 19h30, com entrada mediante doa\u00e7\u00e3o de 1kg de alimento n\u00e3o perec\u00edvel (exceto sal, floc\u00e3o e \u00e1gua pot\u00e1vel) destinado \u00e0 Vila Santa Luzia, na Estrutural, em parceria com o grupo Panelas Compartilhadas. As apresenta\u00e7\u00f5es trazem hist\u00f3rias leves, educativas e interativas, abordando valores como amizade, coopera\u00e7\u00e3o e o verdadeiro significado da P\u00e1scoa. A programa\u00e7\u00e3o inclui ainda o Musical P\u00e1scoa Broadway, com apresenta\u00e7\u00e3o no dia 20 de mar\u00e7o, \u00e0s 19h30, marcando a abertura oficial do evento. 24\/03 &#8211; P\u00e1scoa no S\u00edtio No clima acolhedor do campo, personagens queridos vivem uma aventura divertida para salvar a celebra\u00e7\u00e3o da P\u00e1scoa. Uma hist\u00f3ria leve, educativa e interativa. Apresenta\u00e7\u00e3o grupo Starter Entretenimentos. 26\/03 &#8211; O segredo da P\u00e1scoa Um casal de coelhos muito animado est\u00e1 preocupado com a chegada da P\u00e1scoa pois ainda falta muita coisa para arrumar. Essa dupla encantadora conta atrav\u00e9s de muita dan\u00e7a, m\u00fasica e teatro a verdadeira hist\u00f3ria da P\u00e1scoa! Apresenta\u00e7\u00e3o grupo Oja Lai\u00f3. 31\/03 &#8211; O coelhinho Comil\u00e3o P\u00e1scoa est\u00e1 chegando e a f\u00e1brica de ovos de chocolate est\u00e1 a todo vapor para entregar suas encomendas para as crian\u00e7as. S\u00f3 que parece que a produ\u00e7\u00e3o n\u00e3o tem fim, alguns ovos est\u00e3o sumindo. O que ser\u00e1 que o assistente do Coelho da P\u00e1scoa est\u00e1 justificando? Apresenta\u00e7\u00e3o grupo Neia e Nando. 02\/04 &#8211; Fant\u00e1stica F\u00e1brica de Chocolate Uma jornada encantadora dentro de uma f\u00e1brica cheia de surpresa, m\u00fasicas e personagens exc\u00eantricos. Um espet\u00e1culo grandioso, visualmente impactante e com forte apelo familiar. Apresenta\u00e7\u00e3o grupo Starter Entretenimentos. Oficinas Para completar a experi\u00eancia, as oficinas infantis acontecem diariamente, das 16h \u00e0s 22h, com atividades voltadas para crian\u00e7as de 3 a 14 anos. Entre as op\u00e7\u00f5es est\u00e3o pintura em tela, customiza\u00e7\u00e3o de coelhos de gesso, slime, jardinagem e cria\u00e7\u00e3o de um \u201camigo coelho\u201d para levar para casa. As atividades t\u00eam valor de R$ 50,00 por crian\u00e7a. Entre as oficinas dispon\u00edveis est\u00e3o: Coelho de gesso (pintura e personaliza\u00e7\u00e3o de coelhinhos de P\u00e1scoa), Pintura em tela (pequenos artistas criando suas pr\u00f3prias obras), Slime (oficina divertida para produzir e brincar com slime), Cria Amigo Coelho (cria\u00e7\u00e3o de um coelhinho especial para levar para casa) e Jardinagem (plantio e cuidados com pequenas mudas). Agora confira cliques de C\u00e9sar Rebou\u00e7as de alguns dos convidados especiais do Pont\u00e3o do Lago Sul que participaram da noite de abertura dessa &#8220;Floresta Viva&#8221;: Chocolate e divers\u00e3o! P\u00e1scoa Floresta Viva do Pont\u00e3o Lago Sul \/ SHIS Ql 10, Lote 1\/30 Lago Sul &#8211; Bras\u00edlia \u2013 DF \u00a0\/ 20 de mar\u00e7o a 05 de abril \/\u00a0Telefone: (61) 3364-0580 \/ @pontaodolagosul<\/p>\n","protected":false},"author":6,"featured_media":12205,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[48,43],"tags":[],"class_list":["post-12204","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento","category-perambulando"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>N\u00e3o perca a \u201cFloresta Viva\u201d do Pont\u00e3o! - LACKMAN &amp; CO.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N\u00e3o perca a \u201cFloresta Viva\u201d do Pont\u00e3o! - LACKMAN &amp; CO.\" \/>\n<meta property=\"og:description\" content=\"Com programa\u00e7\u00e3o especial, o complexo recebe decora\u00e7\u00e3o tem\u00e1tica, oficinas infantis, espet\u00e1culos teatrais e experi\u00eancias imersivas para toda a fam\u00edlia. At\u00e9 5 de abril, o Pont\u00e3o Lago Sul se transforma em um cen\u00e1rio m\u00e1gico com a chegada da \u201cFloresta Viva\u201d, tema da programa\u00e7\u00e3o especial de P\u00e1scoa de 2026. Inspirado na natureza, o espa\u00e7o ganha uma ambienta\u00e7\u00e3o l\u00fadica e envolvente, com elementos que remetem ao universo encantado da floresta, proporcionando momentos inesquec\u00edveis para visitantes de todas as idades. No Jardim de Eventos, uma floresta decorada com \u00e1rvores cenogr\u00e1ficas, cogumelos e coelhos em uma paleta de tons verdes e terrosos que refor\u00e7am a proposta de conex\u00e3o com a natureza. O ambiente convida o p\u00fablico a vivenciar uma experi\u00eancia sensorial acolhedora, ideal para fam\u00edlias e crian\u00e7as. A grande atra\u00e7\u00e3o deste ano \u00e9 a Toca Encantada, um espa\u00e7o coberto e imersivo, com decora\u00e7\u00e3o especial e cen\u00e1rios instagram\u00e1veis, incluindo elementos como o guardi\u00e3o da floresta, \u00e1rvores e ambienta\u00e7\u00f5es m\u00e1gicas. O acesso \u00e0 \u00e1rea \u00e9 exclusivo para visitantes mediante ingresso. Meia-entrada R$ 20,00 e ingresso inteiro a R$ 40,00 por pessoa. Crian\u00e7as de at\u00e9 8 anos tem entrada gratuita. Meia-entrada mediante a doa\u00e7\u00e3o de 1kg de alimento a ser destinado \u00e0 Vila Santa Luzia na Estrutural em parceria com o grupo Panelas Compartilhadas. Os ingressos poder\u00e3o ser adquiridos na loja do Pont\u00e3o situada na Floresta Viva, ou nos restaurantes e quiosques do Pont\u00e3o Lago Sul participantes da a\u00e7\u00e3o, estes com retiradas gratuitas mediante notas fiscais com valor m\u00ednimo de consuma\u00e7\u00e3o de R$150,00, para restaurantes, e R$50,00 para quiosques participantes. Programa\u00e7\u00e3o cultural Al\u00e9m da decora\u00e7\u00e3o tem\u00e1tica, o p\u00fablico poder\u00e1 aproveitar uma programa\u00e7\u00e3o completa com espet\u00e1culos teatrais, oficinas criativas e apresenta\u00e7\u00f5es musicais. Entre os destaques est\u00e3o as pe\u00e7as infantis realizadas \u00e0s ter\u00e7as e quintas-feiras, das 18h30 \u00e0s 19h30, com entrada mediante doa\u00e7\u00e3o de 1kg de alimento n\u00e3o perec\u00edvel (exceto sal, floc\u00e3o e \u00e1gua pot\u00e1vel) destinado \u00e0 Vila Santa Luzia, na Estrutural, em parceria com o grupo Panelas Compartilhadas. As apresenta\u00e7\u00f5es trazem hist\u00f3rias leves, educativas e interativas, abordando valores como amizade, coopera\u00e7\u00e3o e o verdadeiro significado da P\u00e1scoa. A programa\u00e7\u00e3o inclui ainda o Musical P\u00e1scoa Broadway, com apresenta\u00e7\u00e3o no dia 20 de mar\u00e7o, \u00e0s 19h30, marcando a abertura oficial do evento. 24\/03 &#8211; P\u00e1scoa no S\u00edtio No clima acolhedor do campo, personagens queridos vivem uma aventura divertida para salvar a celebra\u00e7\u00e3o da P\u00e1scoa. Uma hist\u00f3ria leve, educativa e interativa. Apresenta\u00e7\u00e3o grupo Starter Entretenimentos. 26\/03 &#8211; O segredo da P\u00e1scoa Um casal de coelhos muito animado est\u00e1 preocupado com a chegada da P\u00e1scoa pois ainda falta muita coisa para arrumar. Essa dupla encantadora conta atrav\u00e9s de muita dan\u00e7a, m\u00fasica e teatro a verdadeira hist\u00f3ria da P\u00e1scoa! Apresenta\u00e7\u00e3o grupo Oja Lai\u00f3. 31\/03 &#8211; O coelhinho Comil\u00e3o P\u00e1scoa est\u00e1 chegando e a f\u00e1brica de ovos de chocolate est\u00e1 a todo vapor para entregar suas encomendas para as crian\u00e7as. S\u00f3 que parece que a produ\u00e7\u00e3o n\u00e3o tem fim, alguns ovos est\u00e3o sumindo. O que ser\u00e1 que o assistente do Coelho da P\u00e1scoa est\u00e1 justificando? Apresenta\u00e7\u00e3o grupo Neia e Nando. 02\/04 &#8211; Fant\u00e1stica F\u00e1brica de Chocolate Uma jornada encantadora dentro de uma f\u00e1brica cheia de surpresa, m\u00fasicas e personagens exc\u00eantricos. Um espet\u00e1culo grandioso, visualmente impactante e com forte apelo familiar. Apresenta\u00e7\u00e3o grupo Starter Entretenimentos. Oficinas Para completar a experi\u00eancia, as oficinas infantis acontecem diariamente, das 16h \u00e0s 22h, com atividades voltadas para crian\u00e7as de 3 a 14 anos. Entre as op\u00e7\u00f5es est\u00e3o pintura em tela, customiza\u00e7\u00e3o de coelhos de gesso, slime, jardinagem e cria\u00e7\u00e3o de um \u201camigo coelho\u201d para levar para casa. As atividades t\u00eam valor de R$ 50,00 por crian\u00e7a. Entre as oficinas dispon\u00edveis est\u00e3o: Coelho de gesso (pintura e personaliza\u00e7\u00e3o de coelhinhos de P\u00e1scoa), Pintura em tela (pequenos artistas criando suas pr\u00f3prias obras), Slime (oficina divertida para produzir e brincar com slime), Cria Amigo Coelho (cria\u00e7\u00e3o de um coelhinho especial para levar para casa) e Jardinagem (plantio e cuidados com pequenas mudas). Agora confira cliques de C\u00e9sar Rebou\u00e7as de alguns dos convidados especiais do Pont\u00e3o do Lago Sul que participaram da noite de abertura dessa &#8220;Floresta Viva&#8221;: Chocolate e divers\u00e3o! P\u00e1scoa Floresta Viva do Pont\u00e3o Lago Sul \/ SHIS Ql 10, Lote 1\/30 Lago Sul &#8211; Bras\u00edlia \u2013 DF \u00a0\/ 20 de mar\u00e7o a 05 de abril \/\u00a0Telefone: (61) 3364-0580 \/ @pontaodolagosul\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/\" \/>\n<meta property=\"og:site_name\" content=\"LACKMAN &amp; CO.\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-24T23:15:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-27T23:41:36+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-35-1536x1024-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gilberto Evangelista - Colunista\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilberto Evangelista - Colunista\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/\"},\"author\":{\"name\":\"Gilberto Evangelista - Colunista\",\"@id\":\"https:\/\/lackman.com.br\/#\/schema\/person\/8a2355f699593d21d4f0d25b69db5747\"},\"headline\":\"N\u00e3o perca a \u201cFloresta Viva\u201d do Pont\u00e3o!\",\"datePublished\":\"2026-03-24T23:15:38+00:00\",\"dateModified\":\"2026-03-27T23:41:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/\"},\"wordCount\":935,\"publisher\":{\"@id\":\"https:\/\/lackman.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-35-1536x1024-1.png\",\"articleSection\":[\"Entretenimento\",\"Perambulando\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/\",\"url\":\"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/\",\"name\":\"N\u00e3o perca a \u201cFloresta Viva\u201d do Pont\u00e3o! - LACKMAN &amp; CO.\",\"isPartOf\":{\"@id\":\"https:\/\/lackman.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-35-1536x1024-1.png\",\"datePublished\":\"2026-03-24T23:15:38+00:00\",\"dateModified\":\"2026-03-27T23:41:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/#primaryimage\",\"url\":\"https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-35-1536x1024-1.png\",\"contentUrl\":\"https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-35-1536x1024-1.png\",\"width\":1536,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/lackman.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"N\u00e3o perca a \u201cFloresta Viva\u201d do Pont\u00e3o!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lackman.com.br\/#website\",\"url\":\"https:\/\/lackman.com.br\/\",\"name\":\"LACKMAN &amp; CO.\",\"description\":\"VIDA | MODA | ARTE\",\"publisher\":{\"@id\":\"https:\/\/lackman.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lackman.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lackman.com.br\/#organization\",\"name\":\"LACKMAN &amp; CO.\",\"url\":\"https:\/\/lackman.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/lackman.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lackman.com.br\/wp-content\/uploads\/2023\/06\/Logotipo_preto-1.png\",\"contentUrl\":\"https:\/\/lackman.com.br\/wp-content\/uploads\/2023\/06\/Logotipo_preto-1.png\",\"width\":739,\"height\":393,\"caption\":\"LACKMAN &amp; CO.\"},\"image\":{\"@id\":\"https:\/\/lackman.com.br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/lackman.com.br\/#\/schema\/person\/8a2355f699593d21d4f0d25b69db5747\",\"name\":\"Gilberto Evangelista - Colunista\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/lackman.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cea9badf02f8a90f7a745f2cbea45fda61f65711ec015e2faf3809cca6337c28?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cea9badf02f8a90f7a745f2cbea45fda61f65711ec015e2faf3809cca6337c28?s=96&d=mm&r=g\",\"caption\":\"Gilberto Evangelista - Colunista\"},\"description\":\"Jornalista e globetrotter.\",\"url\":\"https:\/\/lackman.com.br\/index.php\/author\/gilberto-brito\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"N\u00e3o perca a \u201cFloresta Viva\u201d do Pont\u00e3o! - LACKMAN &amp; CO.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/","og_locale":"pt_BR","og_type":"article","og_title":"N\u00e3o perca a \u201cFloresta Viva\u201d do Pont\u00e3o! - LACKMAN &amp; CO.","og_description":"Com programa\u00e7\u00e3o especial, o complexo recebe decora\u00e7\u00e3o tem\u00e1tica, oficinas infantis, espet\u00e1culos teatrais e experi\u00eancias imersivas para toda a fam\u00edlia. At\u00e9 5 de abril, o Pont\u00e3o Lago Sul se transforma em um cen\u00e1rio m\u00e1gico com a chegada da \u201cFloresta Viva\u201d, tema da programa\u00e7\u00e3o especial de P\u00e1scoa de 2026. Inspirado na natureza, o espa\u00e7o ganha uma ambienta\u00e7\u00e3o l\u00fadica e envolvente, com elementos que remetem ao universo encantado da floresta, proporcionando momentos inesquec\u00edveis para visitantes de todas as idades. No Jardim de Eventos, uma floresta decorada com \u00e1rvores cenogr\u00e1ficas, cogumelos e coelhos em uma paleta de tons verdes e terrosos que refor\u00e7am a proposta de conex\u00e3o com a natureza. O ambiente convida o p\u00fablico a vivenciar uma experi\u00eancia sensorial acolhedora, ideal para fam\u00edlias e crian\u00e7as. A grande atra\u00e7\u00e3o deste ano \u00e9 a Toca Encantada, um espa\u00e7o coberto e imersivo, com decora\u00e7\u00e3o especial e cen\u00e1rios instagram\u00e1veis, incluindo elementos como o guardi\u00e3o da floresta, \u00e1rvores e ambienta\u00e7\u00f5es m\u00e1gicas. O acesso \u00e0 \u00e1rea \u00e9 exclusivo para visitantes mediante ingresso. Meia-entrada R$ 20,00 e ingresso inteiro a R$ 40,00 por pessoa. Crian\u00e7as de at\u00e9 8 anos tem entrada gratuita. Meia-entrada mediante a doa\u00e7\u00e3o de 1kg de alimento a ser destinado \u00e0 Vila Santa Luzia na Estrutural em parceria com o grupo Panelas Compartilhadas. Os ingressos poder\u00e3o ser adquiridos na loja do Pont\u00e3o situada na Floresta Viva, ou nos restaurantes e quiosques do Pont\u00e3o Lago Sul participantes da a\u00e7\u00e3o, estes com retiradas gratuitas mediante notas fiscais com valor m\u00ednimo de consuma\u00e7\u00e3o de R$150,00, para restaurantes, e R$50,00 para quiosques participantes. Programa\u00e7\u00e3o cultural Al\u00e9m da decora\u00e7\u00e3o tem\u00e1tica, o p\u00fablico poder\u00e1 aproveitar uma programa\u00e7\u00e3o completa com espet\u00e1culos teatrais, oficinas criativas e apresenta\u00e7\u00f5es musicais. Entre os destaques est\u00e3o as pe\u00e7as infantis realizadas \u00e0s ter\u00e7as e quintas-feiras, das 18h30 \u00e0s 19h30, com entrada mediante doa\u00e7\u00e3o de 1kg de alimento n\u00e3o perec\u00edvel (exceto sal, floc\u00e3o e \u00e1gua pot\u00e1vel) destinado \u00e0 Vila Santa Luzia, na Estrutural, em parceria com o grupo Panelas Compartilhadas. As apresenta\u00e7\u00f5es trazem hist\u00f3rias leves, educativas e interativas, abordando valores como amizade, coopera\u00e7\u00e3o e o verdadeiro significado da P\u00e1scoa. A programa\u00e7\u00e3o inclui ainda o Musical P\u00e1scoa Broadway, com apresenta\u00e7\u00e3o no dia 20 de mar\u00e7o, \u00e0s 19h30, marcando a abertura oficial do evento. 24\/03 &#8211; P\u00e1scoa no S\u00edtio No clima acolhedor do campo, personagens queridos vivem uma aventura divertida para salvar a celebra\u00e7\u00e3o da P\u00e1scoa. Uma hist\u00f3ria leve, educativa e interativa. Apresenta\u00e7\u00e3o grupo Starter Entretenimentos. 26\/03 &#8211; O segredo da P\u00e1scoa Um casal de coelhos muito animado est\u00e1 preocupado com a chegada da P\u00e1scoa pois ainda falta muita coisa para arrumar. Essa dupla encantadora conta atrav\u00e9s de muita dan\u00e7a, m\u00fasica e teatro a verdadeira hist\u00f3ria da P\u00e1scoa! Apresenta\u00e7\u00e3o grupo Oja Lai\u00f3. 31\/03 &#8211; O coelhinho Comil\u00e3o P\u00e1scoa est\u00e1 chegando e a f\u00e1brica de ovos de chocolate est\u00e1 a todo vapor para entregar suas encomendas para as crian\u00e7as. S\u00f3 que parece que a produ\u00e7\u00e3o n\u00e3o tem fim, alguns ovos est\u00e3o sumindo. O que ser\u00e1 que o assistente do Coelho da P\u00e1scoa est\u00e1 justificando? Apresenta\u00e7\u00e3o grupo Neia e Nando. 02\/04 &#8211; Fant\u00e1stica F\u00e1brica de Chocolate Uma jornada encantadora dentro de uma f\u00e1brica cheia de surpresa, m\u00fasicas e personagens exc\u00eantricos. Um espet\u00e1culo grandioso, visualmente impactante e com forte apelo familiar. Apresenta\u00e7\u00e3o grupo Starter Entretenimentos. Oficinas Para completar a experi\u00eancia, as oficinas infantis acontecem diariamente, das 16h \u00e0s 22h, com atividades voltadas para crian\u00e7as de 3 a 14 anos. Entre as op\u00e7\u00f5es est\u00e3o pintura em tela, customiza\u00e7\u00e3o de coelhos de gesso, slime, jardinagem e cria\u00e7\u00e3o de um \u201camigo coelho\u201d para levar para casa. As atividades t\u00eam valor de R$ 50,00 por crian\u00e7a. Entre as oficinas dispon\u00edveis est\u00e3o: Coelho de gesso (pintura e personaliza\u00e7\u00e3o de coelhinhos de P\u00e1scoa), Pintura em tela (pequenos artistas criando suas pr\u00f3prias obras), Slime (oficina divertida para produzir e brincar com slime), Cria Amigo Coelho (cria\u00e7\u00e3o de um coelhinho especial para levar para casa) e Jardinagem (plantio e cuidados com pequenas mudas). Agora confira cliques de C\u00e9sar Rebou\u00e7as de alguns dos convidados especiais do Pont\u00e3o do Lago Sul que participaram da noite de abertura dessa &#8220;Floresta Viva&#8221;: Chocolate e divers\u00e3o! P\u00e1scoa Floresta Viva do Pont\u00e3o Lago Sul \/ SHIS Ql 10, Lote 1\/30 Lago Sul &#8211; Bras\u00edlia \u2013 DF \u00a0\/ 20 de mar\u00e7o a 05 de abril \/\u00a0Telefone: (61) 3364-0580 \/ @pontaodolagosul","og_url":"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/","og_site_name":"LACKMAN &amp; CO.","article_published_time":"2026-03-24T23:15:38+00:00","article_modified_time":"2026-03-27T23:41:36+00:00","og_image":[{"width":1536,"height":1024,"url":"http:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-35-1536x1024-1.png","type":"image\/png"}],"author":"Gilberto Evangelista - Colunista","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gilberto Evangelista - Colunista","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/#article","isPartOf":{"@id":"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/"},"author":{"name":"Gilberto Evangelista - Colunista","@id":"https:\/\/lackman.com.br\/#\/schema\/person\/8a2355f699593d21d4f0d25b69db5747"},"headline":"N\u00e3o perca a \u201cFloresta Viva\u201d do Pont\u00e3o!","datePublished":"2026-03-24T23:15:38+00:00","dateModified":"2026-03-27T23:41:36+00:00","mainEntityOfPage":{"@id":"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/"},"wordCount":935,"publisher":{"@id":"https:\/\/lackman.com.br\/#organization"},"image":{"@id":"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/#primaryimage"},"thumbnailUrl":"https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-35-1536x1024-1.png","articleSection":["Entretenimento","Perambulando"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/","url":"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/","name":"N\u00e3o perca a \u201cFloresta Viva\u201d do Pont\u00e3o! - LACKMAN &amp; CO.","isPartOf":{"@id":"https:\/\/lackman.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/#primaryimage"},"image":{"@id":"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/#primaryimage"},"thumbnailUrl":"https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-35-1536x1024-1.png","datePublished":"2026-03-24T23:15:38+00:00","dateModified":"2026-03-27T23:41:36+00:00","breadcrumb":{"@id":"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/#primaryimage","url":"https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-35-1536x1024-1.png","contentUrl":"https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-35-1536x1024-1.png","width":1536,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/lackman.com.br\/index.php\/2026\/03\/24\/nao-perca-a-floresta-viva-do-pontao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lackman.com.br\/"},{"@type":"ListItem","position":2,"name":"N\u00e3o perca a \u201cFloresta Viva\u201d do Pont\u00e3o!"}]},{"@type":"WebSite","@id":"https:\/\/lackman.com.br\/#website","url":"https:\/\/lackman.com.br\/","name":"LACKMAN &amp; CO.","description":"VIDA | MODA | ARTE","publisher":{"@id":"https:\/\/lackman.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lackman.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/lackman.com.br\/#organization","name":"LACKMAN &amp; CO.","url":"https:\/\/lackman.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lackman.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/lackman.com.br\/wp-content\/uploads\/2023\/06\/Logotipo_preto-1.png","contentUrl":"https:\/\/lackman.com.br\/wp-content\/uploads\/2023\/06\/Logotipo_preto-1.png","width":739,"height":393,"caption":"LACKMAN &amp; CO."},"image":{"@id":"https:\/\/lackman.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/lackman.com.br\/#\/schema\/person\/8a2355f699593d21d4f0d25b69db5747","name":"Gilberto Evangelista - Colunista","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lackman.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cea9badf02f8a90f7a745f2cbea45fda61f65711ec015e2faf3809cca6337c28?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cea9badf02f8a90f7a745f2cbea45fda61f65711ec015e2faf3809cca6337c28?s=96&d=mm&r=g","caption":"Gilberto Evangelista - Colunista"},"description":"Jornalista e globetrotter.","url":"https:\/\/lackman.com.br\/index.php\/author\/gilberto-brito\/"}]}},"rttpg_featured_image_url":{"full":["https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-35-1536x1024-1.png",1536,1024,false],"landscape":["https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-35-1536x1024-1.png",1536,1024,false],"portraits":["https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-35-1536x1024-1.png",1536,1024,false],"thumbnail":["https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-35-1536x1024-1-150x150.png",150,150,true],"medium":["https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-35-1536x1024-1-300x200.png",300,200,true],"large":["https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-35-1536x1024-1-1024x683.png",1024,683,true],"RoboGalleryMansoryImagesCenter":["https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-35-1536x1024-1-600x1024.png",600,1024,true],"RoboGalleryPreload":["https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-35-1536x1024-1-100x67.png",100,67,true],"1536x1536":["https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-35-1536x1024-1.png",1536,1024,false],"2048x2048":["https:\/\/lackman.com.br\/wp-content\/uploads\/2026\/03\/FLORESTA_ENCANTADA_PONTAO-35-1536x1024-1.png",1536,1024,false]},"rttpg_author":{"display_name":"Gilberto Evangelista - Colunista","author_link":"https:\/\/lackman.com.br\/index.php\/author\/gilberto-brito\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/lackman.com.br\/index.php\/category\/arte\/entretenimento\/\" rel=\"category tag\">Entretenimento<\/a> <a href=\"https:\/\/lackman.com.br\/index.php\/category\/vida\/perambulando\/\" rel=\"category tag\">Perambulando<\/a>","rttpg_excerpt":"Com programa\u00e7\u00e3o especial, o complexo recebe decora\u00e7\u00e3o tem\u00e1tica, oficinas infantis, espet\u00e1culos teatrais e experi\u00eancias imersivas para toda a fam\u00edlia. At\u00e9 5 de abril, o Pont\u00e3o Lago Sul se transforma em um cen\u00e1rio m\u00e1gico com a chegada da \u201cFloresta Viva\u201d, tema da programa\u00e7\u00e3o especial de P\u00e1scoa de 2026. Inspirado na natureza, o espa\u00e7o ganha uma ambienta\u00e7\u00e3o&hellip;","_links":{"self":[{"href":"https:\/\/lackman.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lackman.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lackman.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lackman.com.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lackman.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=12204"}],"version-history":[{"count":3,"href":"https:\/\/lackman.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12204\/revisions"}],"predecessor-version":[{"id":12221,"href":"https:\/\/lackman.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12204\/revisions\/12221"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lackman.com.br\/index.php\/wp-json\/wp\/v2\/media\/12205"}],"wp:attachment":[{"href":"https:\/\/lackman.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=12204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lackman.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=12204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lackman.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=12204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}